{"id":261,"date":"2023-03-29T14:57:44","date_gmt":"2023-03-29T14:57:44","guid":{"rendered":"https:\/\/hitwardhini.org\/?page_id=261"},"modified":"2023-05-01T20:44:26","modified_gmt":"2023-05-01T15:14:26","slug":"contact-us-2","status":"publish","type":"page","link":"https:\/\/hitwardhini.org\/index.php\/contact-us-2\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"261\" class=\"elementor elementor-261\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a9816e6 elementor-section-content-middle elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1a9816e6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41d19c5b\" data-id=\"41d19c5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-108e75d4 elementor-widget elementor-widget-heading\" data-id=\"108e75d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h6 class=\"elementor-heading-title elementor-size-large\">Contact<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556749f2 elementor-widget elementor-widget-heading\" data-id=\"556749f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-medium\">+91 89564 80895<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3762806c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"3762806c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Village:Jambhulpada \n\nTal.: Sudhagad \n\n          Dist.: Raigad\n \nMAHARASHTRA  410205 <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0f843 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"8e0f843\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">E-mail: hitwardhini.sabha@yahoo.co.in<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7169951 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7169951\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f0a658\" data-id=\"7f0a658\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82edc2a elementor-widget elementor-widget-image\" data-id=\"82edc2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1636\" height=\"724\" src=\"https:\/\/hitwardhini.org\/wp-content\/uploads\/2023\/04\/SHS-on-Map-3.png\" class=\"attachment-full size-full wp-image-1980\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/hitwardhini.org\/wp-content\/uploads\/2023\/04\/SHS-on-Map-3.png 1636w, https:\/\/hitwardhini.org\/wp-content\/uploads\/2023\/04\/SHS-on-Map-3-1536x680.png 1536w\" sizes=\"(max-width: 1636px) 100vw, 1636px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact +91 89564 80895 Village:Jambhulpada Tal.: Sudhagad Dist.: Raigad MAHARASHTRA 410205 E-mail: hitwardhini.sabha@yahoo.co.in<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/pages\/261"}],"collection":[{"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":274,"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/pages\/261\/revisions"}],"predecessor-version":[{"id":4644,"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/pages\/261\/revisions\/4644"}],"wp:attachment":[{"href":"https:\/\/hitwardhini.org\/index.php\/wp-json\/wp\/v2\/media?parent=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}